{"id":23856,"date":"2019-01-27T00:01:30","date_gmt":"2019-01-27T00:01:30","guid":{"rendered":"http:\/\/gecousb.com.ve\/index.php\/2019\/01\/27\/guias-cabello-gonzalez-ma-2115-5\/"},"modified":"2019-01-27T00:01:30","modified_gmt":"2019-01-27T00:01:30","slug":"guias-cabello-gonzalez-ma-2115-5","status":"publish","type":"post","link":"https:\/\/gecousb.com.ve\/index.php\/2019\/01\/27\/guias-cabello-gonzalez-ma-2115-5\/","title":{"rendered":"Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)"},"content":{"rendered":"<ul class='seccion-list'>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 1.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 1.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 10.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 10.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 11.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 11.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 12.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 12.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 14.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 14.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 15.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 15.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 16.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 16.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 17.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 17.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 18.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 18.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 2.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 2.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 3.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 3.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 4.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 4.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 5.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 5.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 6.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 6.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 8.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 8.pdf<\/a><\/li>\n<li><a href='http:\/\/gecousb.com.ve\/guias\/GECO\/Matem\u00e1ticas 4 (MA-2115)\/Gu\u00edas Cabello-Gonz\u00e1lez (MA-2115)\/MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 9.pdf'>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 9.pdf<\/a><\/li>\n","protected":false},"excerpt":{"rendered":"<p>MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 1.pdf MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 10.pdf MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 11.pdf MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 12.pdf MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 14.pdf MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 15.pdf MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase 16.pdf MA-2115 Cabello Y Marcos Gonz\u00e1lez Clase [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/gecousb.com.ve\/index.php\/wp-json\/wp\/v2\/posts\/23856"}],"collection":[{"href":"https:\/\/gecousb.com.ve\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gecousb.com.ve\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/gecousb.com.ve\/index.php\/wp-json\/wp\/v2\/comments?post=23856"}],"version-history":[{"count":0,"href":"https:\/\/gecousb.com.ve\/index.php\/wp-json\/wp\/v2\/posts\/23856\/revisions"}],"wp:attachment":[{"href":"https:\/\/gecousb.com.ve\/index.php\/wp-json\/wp\/v2\/media?parent=23856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gecousb.com.ve\/index.php\/wp-json\/wp\/v2\/categories?post=23856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gecousb.com.ve\/index.php\/wp-json\/wp\/v2\/tags?post=23856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}